{"id":55,"date":"2024-07-18T17:32:33","date_gmt":"2024-07-18T17:32:33","guid":{"rendered":"https:\/\/llproducts1.wpenginepowered.com\/temp-de\/?page_id=55"},"modified":"2024-11-12T01:00:12","modified_gmt":"2024-11-12T01:00:12","slug":"homepage","status":"publish","type":"page","link":"https:\/\/www.llproducts.com\/temp-de\/","title":{"rendered":"Homepage"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_slider et_pb_slider_0 home-slider et_pb_slider_fullwidth_off\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_0  et_pb_css_mix_blend_mode et_pb_bg_layout_light et_pb_media_alignment_center et-pb-active-slide\" data-slide-id=\"et_pb_slide_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<div class=\"et_pb_slide_content\"><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg\" width=\"115\" height=\"97\" alt=\"Nissan\" class=\"wp-image-11055 alignnone size-full\" \/><\/p>\n<p>L&amp;L Products has been awarded the 2024 Regional Supplier Quality Master Certificate from Nissan North America. This marks the third time since 2020 that L&amp;L has received this award.<\/p><\/div>\n\t\t\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button\" href=\"\/news-events\/ll-products-awarded-2024-regional-supplier-quality-master-certificate-from-nissan\">Read More<\/a><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_1  et_pb_css_mix_blend_mode et_pb_bg_layout_light et_pb_media_alignment_center\" data-slide-id=\"et_pb_slide_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<div class=\"et_pb_slide_content\"><h2>Recipient of SILVER Medal by EcoVadis<\/h2>\n<p>L&amp;L Products has been awarded a SILVER medal by EcoVadis in 2024 in recognition of its ongoing commitment to sustainability. This is the 7th year L&amp;L Products has participated in EcoVadis.<\/p><\/div>\n\t\t\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button\" href=\"\/company\/corporate-social-responsibility\/\">Read More<\/a><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_2  et_pb_css_mix_blend_mode et_pb_bg_layout_light et_pb_media_alignment_center\" data-slide-id=\"et_pb_slide_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<div class=\"et_pb_slide_content\"><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/csm_phaster_logo_tm_77822f33c5.jpg\" width=\"550\" height=\"47\" alt=\"PHASTER\u2122\" class=\"wp-image-1107 alignnone size-full\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/csm_phaster_logo_tm_77822f33c5.jpg 550w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/csm_phaster_logo_tm_77822f33c5-480x41.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 550px, 100vw\" \/><\/p>\n<p>The proprietary two-component ambient temperature curing technology is HERE. Discover PHASTER\u2122, L&amp;L\u2019s new Transformative Technology that will re-define the way you Bond, Seal, Reinforce and Repair.<\/p><\/div>\n\t\t\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button\" href=\"https:\/\/phaster.llproducts.com\/\" target=\"_blank\">Read More<\/a><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_3 et_clickable et_pb_section_video et_pb_preload  et_pb_css_mix_blend_mode et_pb_bg_layout_light et_pb_media_alignment_center\" data-slide-id=\"et_pb_slide_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<span class=\"et_pb_section_video_bg  \">\n\t\t\t\t\t\n\t\t\t<video loop=\"loop\" autoplay playsinline muted >\n\t\t\t\t<source type=\"video\/mp4\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/Insitucore-header1800x-680_1.mp4\" \/>\n\t\t\t\t\n\t\t\t<\/video>\n\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Driven by Technology<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\">L&L Products combines expertise in materials science, advanced engineering, and manufacturing process optimization for customers to develop unique solutions that deliver structural reinforcement, substrate bonding, static sealing, and acoustic improvement for automotive, aerospace, commercial vehicle, construction, and consumer products applications. For nearly 70 years, our skilled chemists, scientists, and engineers have collaborated with customers around the world to make products lighter, stronger, and quieter.<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"\/company\/locations\"><span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" width=\"804\" height=\"437\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/07\/LL-Products-Locations-Map.jpg\" alt=\"\" title=\"LL Products Locations Map\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/07\/LL-Products-Locations-Map.jpg 804w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/07\/LL-Products-Locations-Map-480x261.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 804px, 100vw\" class=\"wp-image-64\" \/><\/span><\/a>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_right et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_pb_bg_layout_light et_block_module\" href=\"\/company\/locations\">Click here for our location details<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_2 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Our Solutions<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_3_4 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p class=\"text-uppercase\"><strong>CUSTOMIZED MATERIAL SCIENCE FOR MULTIPLE INDUSTRIES.<\/strong><\/p>\n<p><span>We are proud to be an innovative development partner to a vast customer base, providing them with unique material formulations and engineering solutions for lighter, stronger, quieter products.<\/span><\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_3 solutions-home et_pb_equal_columns et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_5 et_clickable  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><span>\n  01\n<\/span>\n<h3>\n  <strong>Acoustic<\/strong>\n<\/h3>\n<hr \/>\n\n  A new silence.\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_6 et_clickable  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><span>\n  02\n<\/span>\n<h3>\n  <strong>Bond<\/strong>\n<\/h3>\n<hr \/>\n\n  Proven solutions.\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_7 et_clickable  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><span>\n  03\n<\/span>\n<h3>\n  <strong>Reinforce<\/strong>\n<\/h3>\n<hr \/>\n\n  Strength first.\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_8 et_clickable  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><span>\n  04\n<\/span>\n<h3>\n  <strong>Seal<\/strong>\n<\/h3>\n<hr \/>\n\n  Without compromises.\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_9 et_clickable  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_4\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><span>\n  05\n<\/span>\n<h3>\n  <strong>Thermal<\/strong>\n<\/h3>\n<hr \/>\n\n  Made for heat.\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_10  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_1_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_1 et_pb_bg_layout_light et_block_module\" href=\"\/products-solutions\/\">Products &amp; Solutions<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_with_border et_d4_element et_pb_section et_pb_section_3  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_5  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_11  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_4  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>News<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_with_border et_pb_module et_d4_element et_pb_blog_0 align-blog  et_pb_css_mix_blend_mode et_pb_blog_grid_wrapper et_pb_bg_layout_light\">\n\t\t\t\t\t<div class=\"et_pb_blog_grid clearfix \">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_ajax_pagination_container\">\n\t\t\t\t\t\t<div class=\"et_pb_salvattore_content\" data-columns>\n\t\t\t<article id=\"post-11786\" class=\"et_pb_post clearfix et_pb_blog_item_0_0 post-11786 post type-post status-publish format-standard has-post-thumbnail hentry category-news post-year-19\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/detroit-free-press-ernennt-ll-products-zum-gewinner-des-michigan-top-workplaces-2024-award\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/csm_top_workplaces_2024_slider_c83c413819-400x250.jpg\" alt=\"Detroit Free Press Ernennt L&#038;l Products Zum Gewinner Des Michigan Top Workplaces 2024 Award\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/csm_top_workplaces_2024_slider_c83c413819.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/csm_top_workplaces_2024_slider_c83c413819-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/detroit-free-press-ernennt-ll-products-zum-gewinner-des-michigan-top-workplaces-2024-award\/\">Detroit Free Press Ernennt L&#038;l Products Zum Gewinner Des Michigan Top Workplaces 2024 Award<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Nov 18, 2024<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>&amp;L Products wurde von der Detroit Free Press als einer der Top Arbeitspl\u00e4tze 2024 ausgezeichnet. Diese Liste basiert ausschlie\u00dflich...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-11740\" class=\"et_pb_post clearfix et_pb_blog_item_0_1 post-11740 post type-post status-publish format-standard has-post-thumbnail hentry category-news post-year-19\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/composites-in-manufacturing-features-how-best-to-engineer-the-ideal-foam-core-composite-manufacturing-solution-insitucoretm\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/insitucore_in_composites_in_manufacturing-400x250.jpg\" alt=\"Composites in Manufacturing features how best to engineer the ideal foam core composite manufacturing solution &#8211; InsituCore\u2122\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/insitucore_in_composites_in_manufacturing.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/insitucore_in_composites_in_manufacturing-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/composites-in-manufacturing-features-how-best-to-engineer-the-ideal-foam-core-composite-manufacturing-solution-insitucoretm\/\">Composites in Manufacturing features how best to engineer the ideal foam core composite manufacturing solution &#8211; InsituCore\u2122<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Nov 8, 2024<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>The \"why\" behind InsituCore\u2122 is featured in a recent article in Composites in Manufacturing. The article outlines typical processes that...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-10043\" class=\"et_pb_post clearfix et_pb_blog_item_0_2 post-10043 post type-post status-publish format-standard has-post-thumbnail hentry category-news post-year-19\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/ll-products-awarded-2024-regional-supplier-quality-master-certificate-from-nissan\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/nissan_quality_award_2024_ll_products_2-400x250.jpg\" alt=\"L&#038;L Products erh\u00e4lt das 2024 Regional Supplier Quality Master Zertifikat von Nissan\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/nissan_quality_award_2024_ll_products_2.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/nissan_quality_award_2024_ll_products_2-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/ll-products-awarded-2024-regional-supplier-quality-master-certificate-from-nissan\/\">L&#038;L Products erh\u00e4lt das 2024 Regional Supplier Quality Master Zertifikat von Nissan<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Oct 11, 2024<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>L&amp;L Products ist stolz verk\u00fcnden zu d\u00fcrfen, dass das Unternehmen mit dem 2024 Regional Supplier Quality Master Zertifikat von Nissan...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_2_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_2 secondary et_pb_bg_layout_light et_block_module\" href=\"\/news-events\/?_sft_category=news\">See All News<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_6  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_12  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_5  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Events<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_with_border et_pb_module et_d4_element et_pb_blog_1 align-blog  et_pb_css_mix_blend_mode et_pb_blog_grid_wrapper et_pb_bg_layout_light\">\n\t\t\t\t\t<div class=\"et_pb_blog_grid clearfix \">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_ajax_pagination_container\">\n\t\t\t\t\t\t<div class=\"et_pb_salvattore_content\" data-columns>\n\t\t\t<article id=\"post-10863\" class=\"et_pb_post clearfix et_pb_blog_item_1_0 post-10863 post type-post status-publish format-standard has-post-thumbnail hentry category-events post-year-74\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/conexpo-con-agg\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/conagg_conexpo_2026-400x250.jpg\" alt=\"CONEXPO-CON\/AGG\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/conagg_conexpo_2026.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/10\/conagg_conexpo_2026-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/conexpo-con-agg\/\">CONEXPO-CON\/AGG<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Mar 3, 2026<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>Date: March 3-7, 2026 Location: Las Vegas, Nevada, USA L&amp;L Products booth number: TBD CONEXPO-CON\/AGG, held every three years, is the...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-10862\" class=\"et_pb_post clearfix et_pb_blog_item_1_1 post-10862 post type-post status-publish format-standard has-post-thumbnail hentry category-events post-year-73\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/the-battery-show-north-america-2025\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_the_battery_show_na_47db6ac9c2-400x250.jpg\" alt=\"The Battery Show North America\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_the_battery_show_na_47db6ac9c2.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_the_battery_show_na_47db6ac9c2-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/the-battery-show-north-america-2025\/\">The Battery Show North America<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Oct 7, 2025<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>Date: October 7-9, 2025 Location: Huntington Place Detroit, MI L&amp;L Products booth number: Booth 605 The Battery Show North America is...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-10861\" class=\"et_pb_post clearfix et_pb_blog_item_1_2 post-10861 post type-post status-publish format-standard has-post-thumbnail hentry category-events post-year-73\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/camx-the-composites-and-advanced-materials-expo-2025\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_camx_fa40fb1ce5-400x250.jpg\" alt=\"CAMX \u2013 the Composites and Advanced Materials Expo\" class=\"\" srcset=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_camx_fa40fb1ce5.jpg 479w, https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/09\/csm_camx_fa40fb1ce5-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.llproducts.com\/temp-de\/news-events\/camx-the-composites-and-advanced-materials-expo-2025\/\">CAMX \u2013 the Composites and Advanced Materials Expo<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\"><span class=\"published\">Sep 8, 2025<\/span><\/p><div class=\"post-content\"><div class=\"post-content-inner et_multi_view_hidden\"><p>Date: September 8-11, 2025 Location: Orange County Convention Center Orlando, Florida, USA L&amp;L Products booth number: K55 CAMX \u2013 the...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_3_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_3 secondary et_pb_bg_layout_light et_block_module\" href=\"\/news-events\/?_sft_category=events\">See All Events<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_4 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_7  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_13  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_6  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Trending Topics<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_8  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_14  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_code et_pb_code_5\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_code_inner\"><script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" data-use-service-core defer><\/script>\n<div class=\"elfsight-app-72e28d3a-cb29-47b9-b42c-d9b80ca2705a\" data-elfsight-app-lazy><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-55","page","type-page","status-publish","hentry"],"acf":[],"dsm_author":{"name":"ryan","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5a0e3c637434ffef209231cff8124b06dd377cef0c619ad38cc2213d74f1a57c?s=96&d=mm&r=g","archive_link":"https:\/\/www.llproducts.com\/temp-de\/news-events\/author\/ryan\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&amp;L Products - Applied Engineering &amp; Materials Science<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.llproducts.com\/temp-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Temp - DE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T01:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/\",\"name\":\"L&L Products - Applied Engineering & Materials Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/11\\\/nissan-logo.jpg\",\"datePublished\":\"2024-07-18T17:32:33+00:00\",\"dateModified\":\"2024-11-12T01:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/11\\\/nissan-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/11\\\/nissan-logo.jpg\",\"width\":115,\"height\":97,\"caption\":\"Nissan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/#website\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/\",\"name\":\"Temp - DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.llproducts.com\\\/temp-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L&L Products - Applied Engineering & Materials Science","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Homepage","og_url":"https:\/\/www.llproducts.com\/temp-de\/","og_site_name":"Temp - DE","article_modified_time":"2024-11-12T01:00:12+00:00","og_image":[{"url":"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.llproducts.com\/temp-de\/","url":"https:\/\/www.llproducts.com\/temp-de\/","name":"L&L Products - Applied Engineering & Materials Science","isPartOf":{"@id":"https:\/\/www.llproducts.com\/temp-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.llproducts.com\/temp-de\/#primaryimage"},"image":{"@id":"https:\/\/www.llproducts.com\/temp-de\/#primaryimage"},"thumbnailUrl":"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg","datePublished":"2024-07-18T17:32:33+00:00","dateModified":"2024-11-12T01:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.llproducts.com\/temp-de\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.llproducts.com\/temp-de\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.llproducts.com\/temp-de\/#primaryimage","url":"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg","contentUrl":"https:\/\/www.llproducts.com\/temp-de\/wp-content\/uploads\/sites\/9\/2024\/11\/nissan-logo.jpg","width":115,"height":97,"caption":"Nissan"},{"@type":"BreadcrumbList","@id":"https:\/\/www.llproducts.com\/temp-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.llproducts.com\/temp-de\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/www.llproducts.com\/temp-de\/#website","url":"https:\/\/www.llproducts.com\/temp-de\/","name":"Temp - DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.llproducts.com\/temp-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/pages\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":0,"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/pages\/55\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.llproducts.com\/temp-de\/wp-json\/wp\/v2\/media?parent=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}