{"id":1029,"date":"2024-10-03T15:12:44","date_gmt":"2024-10-03T15:12:44","guid":{"rendered":"https:\/\/llproducts1.wpenginepowered.com\/zh-cn\/?page_id=1029"},"modified":"2026-07-14T01:45:15","modified_gmt":"2026-07-14T01:45:15","slug":"corporate-social-responsibility","status":"publish","type":"page","link":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/","title":{"rendered":"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_0 et_pb_row et_pb_gutters1 et_block_row inner-title-row\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_2_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg\" alt=\"A woman on a bike\" width=\"1440\" height=\"662\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg 1440w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-1280x588.jpg 1280w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-980x451.jpg 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-480x221.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1440px, 100vw\" class=\"wp-image-11761\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_1 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough et_animated inner-title-col alt-title-col\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>CSR<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module inner-title-2\"><div class=\"et_pb_text_inner\"><h1 class=\"h1--small top-slider-content__headline  \">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb<\/h1>\n<\/div><\/div>\n\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>L&amp;L\u5bfb\u6c42\u521b\u9020\u4e00\u4e2a\u79ef\u6781\u548c\u4e3b\u52a8\u7684\u53ef\u6301\u7eed\u53d1\u5c55\u6587\u5316\uff0c\u5e76\u5bf9\u6240\u6709\u5458\u5de5\u7684\u60f3\u6cd5\u6301\u5f00\u653e\u6001\u5ea6\uff0c\u4ee5\u5e2e\u52a9\u521b\u9020\u548c\u63a8\u52a8\u8fd9\u4e00\u52aa\u529b\u3002<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module wht-btn\" href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2026\/04\/Corporate-Social-Responsibility-Report_2025-Final.pdf\" target=\"_blank\">\u4e0b\u8f09\u4f01\u696d\u793e\u6703\u8cac\u4efb\u901a\u8a0a 2025<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_block_row\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_sidebar_0 et_pb_widget_area clearfix et_pb_widget_area_left et_pb_bg_layout_light et_pb_sidebar_no_border et_pb_module et_block_module breadcrumbs\"><div id=\"block-10\" class=\"et_pb_widget widget_block\"><div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/www.llproducts.com\/zh-cn\/\">Home<\/a><\/span> <span aria-hidden=\"true\" data-icon=\"\ue93c\" class=\"icomoon icon-chevron-right\"><\/span> <span><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/\">\u516c\u53f8<\/a><\/span> <span aria-hidden=\"true\" data-icon=\"\ue93c\" class=\"icomoon icon-chevron-right\"><\/span> <span class=\"breadcrumb_last\" aria-current=\"page\">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb<\/span><\/span><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_specialty et_pb_gutters3 et_block_section\" id=\"page-content\"><div class=\"et_pb_row et_pb_row-1-4_3-4 et_block_row\">\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_single et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_sidebar_1 et_pb_widget_area clearfix et_pb_widget_area_left et_pb_bg_layout_light et_pb_sidebar_no_border et_pb_module et_block_module\"><div id=\"nav_menu-10\" class=\"et_pb_widget widget_nav_menu\"><div class=\"menu-company-menu-container\"><ul id=\"menu-company-menu\" class=\"menu\"><li id=\"menu-item-841\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-841\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/\">\u516c\u53f8<\/a><\/li>\n<li id=\"menu-item-839\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-839\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/%e5%88%9b%e6%96%b0\/\">\u521b\u65b0<\/a><\/li>\n<li id=\"menu-item-840\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-840\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/values\/\">\u4ef7\u503c\u4e0e\u6587\u5316<\/a><\/li>\n<li id=\"menu-item-908\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-908\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/history\/\">\u516c\u53f8\u5386\u53f2<\/a><\/li>\n<li id=\"menu-item-1071\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1071\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/career\/\">\u804c\u4e1a\u751f\u6daf<\/a><\/li>\n<li id=\"menu-item-10779\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-10779\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/locations\/\">\u516c\u53f8\u4f4d\u7f6e<\/a><\/li>\n<li id=\"menu-item-1070\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1070\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/foundations\/\">\u57fa\u91d1\u4f1a<\/a><\/li>\n<li id=\"menu-item-1069\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1069\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/\">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb<\/a><\/li>\n<li id=\"menu-item-10780\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-10780\"><a href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/resource-center\/\">\u8d44\u6e90\u4e2d\u5fc3<\/a><\/li>\n<\/ul><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et_pb_specialty_column et_pb_column_3_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_row_inner_0 et_pb_row_inner et_block_row focus-dot\">\n<div class=\"et_pb_column_inner_0 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>\"\u867d\u7136L&amp;L\u516c\u53f8\u591a\u5e74\u6765\u6709\u4e86\u5de8\u5927\u7684\u53d1\u5c55\uff0c\u4f46\u4ed6\u4eec\u5bf9\u5458\u5de5\u7684\u81ea\u8c6a\u611f\u548c\u5c0a\u91cd\u4ece\u6765\u6ca1\u6709\u51cf\u5c11\u8fc7\u3002\"<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><span style=\"font-size: 16px; color: #717271;\">MARTY ENGLISH \u2013 \u6df7\u5408\u6280\u672f\u5458<\/span><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_1 et_pb_row_inner et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_1 et_pb_column_inner et_pb_column et_pb_column_3_8 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/ll_products_csr.jpg\" width=\"669\" height=\"446\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/ll_products_csr.jpg 669w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/ll_products_csr-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 669px, 100vw\" class=\"wp-image-1033\" title=\"MARTY ENGLISH \u2013 Mixing Technician\" alt=\"MARTY ENGLISH \u2013 Mixing Technician\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_2 et_pb_column_inner et_pb_column et_pb_column_3_8 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2 class=\"after-dot color-blue no-dot\">\u5171\u540c\u4e3a<br \/>\n\u4e00\u4e2a\u5171\u540c\u7684\u76ee\u6807\uff0c\u6211\u4eec\u5728\u4e00\u8d77\u3002<\/h2>\n<\/div><\/div>\n\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>L&amp;L\u4ea7\u54c1\u516c\u53f8\u5171\u540c\u81f4\u529b\u4e8e\u5b9e\u73b0\u4e00\u4e2a\u5171\u540c\u7684\u76ee\u6807\uff1a\"\u6210\u4e3a\u6240\u6709\u4eba\u90fd\u5411\u5f80\u7684\u597d\u5730\u65b9\uff0c\u5de5\u4f5c\u8d28\u91cf\u3001\u4ea7\u54c1\u548c\u5ba2\u6237\u5173\u7cfb\u6c38\u8fdc\u7b2c\u4e00\u3002\"\u6b64\u5916\uff0c\u6211\u4eec\u7684\u4f01\u4e1a\u4ef7\u503c\u89c2\u8ba9\u6211\u4eec\u66f4\u52a0\u5173\u5fc3\u6211\u4eec\u7684\u73af\u5883\uff0c\u6211\u4eec\u7684\u5458\u5de5\uff0c\u6211\u4eec\u7684\u5546\u4e1a\u4f19\u4f34\uff0c\u4ee5\u53ca\u6211\u4eec\u7ecf\u8425\u7684\u793e\u533a\uff0c\u751a\u81f3\u66f4\u591a\u3002\u3002<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_2 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_3 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_dark et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2 class=\"\">\u6211\u4eec\u52c7\u4e8e\u62c5\u5f53<\/h2>\n<\/div><\/div>\n\n<div class=\"et_pb_code_1 et_pb_code et_animated et_pb_module red-boxes\"><div class=\"et_pb_code_inner\"><div class=\"red-box\"><span>\u4e3a\u4e86\u6211\u4eec\u7684\u5730\u7403\u3002<\/span><\/div><\/div><\/div>\n\n<div class=\"et_pb_code_2 et_pb_code et_animated et_pb_module red-boxes\"><div class=\"et_pb_code_inner\"><div class=\"red-box\"><span>\u4e3a\u4e86\u6211\u4eec\u7684\u5458\u5de5\u3002<\/span><\/div><\/div><\/div>\n\n<div class=\"et_pb_code_3 et_pb_code et_animated et_pb_module red-boxes\"><div class=\"et_pb_code_inner\"><div class=\"red-box\"><span>\u4e3a\u4e86\u6211\u4eec\u7684\u5546\u4e1a\u5408\u4f5c\u4f19\u4f34\u3002<\/span><\/div><\/div><\/div>\n\n<div class=\"et_pb_code_4 et_pb_code et_animated et_pb_module red-boxes\"><div class=\"et_pb_code_inner\"><div class=\"red-box\"><span>\u4e3a\u4e86\u6211\u4eec\u7684\u793e\u533a\u548c\u4e16\u754c\u3002<\/span><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_3 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_4 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><blockquote>\n<p>\"L&amp;L\u4ea7\u54c1\u516c\u53f8\u81f4\u529b\u4e8e\u53bb\u3002\u6211\u5f88\u81ea\u8c6a\u80fd\u6210\u4e3a\u8fd9\u4e2a\u9879\u76ee\u7684\u4e00\u90e8\u5206\uff0c\u4ece\u800c\u7167\u987e\u5230\u6211\u4eec\u7684\u5730\u7403\u548c\u6211\u4eec\u7684\u540e\u4ee3\"\u3002<\/p>\n<\/blockquote>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_4 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_5 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_slider_0 et_pb_slider et_pb_slider_fullwidth_off et_slider_auto et_pb_slider_show_image et_slider_speed_20000 et_animated et_pb_module et_block_module csr-slider\"><div class=\"et_pb_slides\">\n<div class=\"et_pb_slide_0 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-0\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_01_for_the_planet.jpg\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_01_for_the_planet.jpg 1280w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_01_for_the_planet-980x551.jpg 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_01_for_the_planet-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" class=\"wp-image-1036\" \/><\/div><div class=\"et_pb_slide_description\"><h3 class=\"et_pb_slide_title\">\u4e3a\u4e86\u6211\u4eec\u7684\u5730\u7403\u3002<\/h3><div class=\"et_pb_slide_content\"><p>\u6211\u4eec\u7684\u76ee\u6807\u662f\u7528\u66f4\u5c11\u7684\u8d44\u6e90\u521b\u9020\u66f4\u597d\u7684\u89e3\u51b3\u65b9\u6848\uff0c\u5e76\u91c7\u53d6\u5b9e\u9645\u884c\u52a8\u51cf\u5c11\u5bf9\u73af\u5883\u7684\u5f71\u54cd\u3002 \u4ece\u4ea7\u54c1\u8bbe\u8ba1\u548c\u5305\u88c5\u5230\u5206\u53d1\u6211\u4eec\u7684\u4ea7\u54c1\u6240\u9700\u7684\u8fd0\u8f93\u5faa\u73af\uff0c\u6211\u4eec\u5de5\u4f5c\u6d41\u7a0b\u7684\u6bcf\u4e2a\u65b9\u9762\u90fd\u4ece\u53ef\u6301\u7eed\u6027\u7684\u89d2\u5ea6\u8003\u8651\u3002 \u6211\u4eec\u7684\u4e3b\u8981\u76ee\u6807\u5305\u62ec\u96f6\u6d6a\u8d39\u548c\u96f6\u73af\u5883\u4e8b\u6545\u3002<\/p>\n<p><a href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2026\/04\/LLP-Corporate-Environmental-Policy_2026_CN.pdf\" target=\"_blank\" rel=\"noopener\"><span>\u4f01\u4e1a\u73af\u5883\u653f\u7b56<\/span><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_1 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-1\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_02_for_our_people.jpg\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_02_for_our_people.jpg 1280w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_02_for_our_people-980x551.jpg 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_02_for_our_people-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" class=\"wp-image-1037\" \/><\/div><div class=\"et_pb_slide_description\"><h3 class=\"et_pb_slide_title\">\u4e3a\u4e86\u6211\u4eec\u7684\u5458\u5de5\u3002<\/h3><div class=\"et_pb_slide_content\"><p>\u827e\u8054\u4ea7\u54c1\u575a\u4fe1\u516c\u5e73\u5bf9\u5f85\u6240\u6709\u4eba\u3002\u6b64\u5916\uff0c\u6211\u4eec\u76f8\u4fe1\uff0c\u516c\u5e73\u3001\u6587\u5316\u591a\u6837\u6027\u548c\u5e73\u7b49\u673a\u4f1a\u6709\u52a9\u4e8e\u6211\u4eec\u6210\u957f\u4e3a\u4e00\u4e2a\u793e\u533a \u3002\u6211\u4eec\u7684\u5065\u5eb7\u4e0e\u5b89\u5168\u653f\u7b56\u548c\u5458\u5de5\u9053\u5fb7\u89c4\u8303\u9f13\u52b1\u5458\u5de5\u4ee5\u5b89\u5168\u3001\u5065\u5eb7\u7684\u65b9\u5f0f\u5de5\u4f5c\u5e76\u8bda\u4fe1\u884c\u4e8b\u3002<\/p>\n<p><a href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2024\/10\/LLP-Corporate-Policy-OHS_2024.12_EN.pdf\" target=\"_blank\" rel=\"noopener\">\u516c\u53f8\u804c\u4e1a\u5065\u5eb7\u548c\u5b89\u5168\u653f\u7b56<\/a><\/p>\n<p><a href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2025\/07\/LLP-Whistleblower-Antiretaliation-Policy_2025_CN.pdf\" target=\"_blank\" rel=\"noopener\">\u53cd\u62a5\u590d\u653f\u7b56<\/a><\/p>\n<p><a href=\"\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/12\/llp_code_of_ethics_2024_chinese.pdf\" target=\"_blank\" rel=\"noopener\">\u96c7\u5458\u9053\u5fb7\u51c6\u5219<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_2 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-2\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_03_for_our_business_partners.jpg\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_03_for_our_business_partners.jpg 1280w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_03_for_our_business_partners-980x551.jpg 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_03_for_our_business_partners-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" class=\"wp-image-1038\" \/><\/div><div class=\"et_pb_slide_description\"><h3 class=\"et_pb_slide_title\">\u4e3a\u4e86\u6211\u4eec\u7684\u5546\u4e1a\u5408\u4f5c\u4f19\u4f34\u3002<\/h3><div class=\"et_pb_slide_content\"><p>\u6211\u4eec\u5bfb\u6c42\u4e0e\u63d0\u4f9b\u521b\u65b0\u4ea7\u54c1\u7684\u5408\u4f5c\u4f19\u4f34\u4e00\u8d77\u5de5\u4f5c\uff0c\u4ed6\u4eec\u613f\u610f\u5171\u540c\u60f3\u8c61\u548c\u5f00\u53d1\u672a\u6765\u7684\u4ea7\u54c1\u3002 \u6211\u4eec\u975e\u5e38\u91cd\u89c6\u6211\u4eec\u7684\u4e1a\u52a1\u5408\u4f5c\u4f19\u4f34\uff0c\u5e76\u76f8\u4fe1\u6211\u4eec\u90fd\u53ef\u4ee5\u5728\u4e3a\u5ba2\u6237\u63d0\u4f9b\u9ad8\u8d28\u91cf\u89e3\u51b3\u65b9\u6848\u65b9\u9762\u53d1\u6325\u4f5c\u7528\u3002 \u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u6211\u4eec\u9009\u62e9\u4e0e\u6211\u4eec\u81ea\u5df1\u7684\u9053\u5fb7\u6807\u51c6\u76f8\u4f3c\u7684\u5408\u4f5c\u4f19\u4f34\u3002<\/p>\n<p><a href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2025\/03\/LLP-Sustainable-Purchasing-Policy_2025_CN.pdf\">\u4f01\u4e1a\u53ef\u6301\u7eed\u91c7\u8d2d\u653f\u7b56<\/a><\/p>\n<p><a href=\"\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/12\/ll_supplier_code_of_conduct_v3_chinese_updated_nov_14_2023.pdf\" target=\"_blank\" rel=\"noopener\">\u4f9b\u5e94\u5546\u884c\u4e3a\u51c6\u5219<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_3 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-3\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_04_for_our_communities.jpg\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_04_for_our_communities.jpg 1280w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_04_for_our_communities-980x551.jpg 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_care_04_for_our_communities-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" class=\"wp-image-1039\" \/><\/div><div class=\"et_pb_slide_description\"><h3 class=\"et_pb_slide_title\">\u4e3a\u4e86\u6211\u4eec\u7684\u793e\u533a\u548c\u4e16\u754c\u3002<\/h3><div class=\"et_pb_slide_content\"><p>\u6211\u4eec\u52aa\u529b\u4f7f\u6211\u4eec\u7684\u793e\u533a\u548c\u6211\u4eec\u6240\u5728\u7684\u5730\u65b9\u53d8\u5f97\u66f4\u597d\u3002 \u591a\u5e74\u6765\uff0c\u6211\u4eec\u4e00\u76f4\u5728\u91c7\u53d6\u884c\u52a8\uff0c\u901a\u8fc7\u5458\u5de5\u9a71\u52a8\u53d1\u8d77\u7684\u4e3e\u63aa\u9020\u798f\u6211\u4eec\u7684\u5bb6\u5ead\u793e\u533a\u3002 \u6211\u4eec\u7684\u652f\u6301\u4e3a\u4eca\u5929\u548c\u6211\u4eec\u7684\u540e\u4ee3\u63d0\u4f9b\u4e86\u673a\u4f1a\u548c\u8fdb\u6b65\u3002<\/p>\n<p><a href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2025\/04\/CSR-Report-2024.pdf\" target=\"_blank\" rel=\"noopener\">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u4ea4\u6d41 2024<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_5 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_6 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_slider_1 et_pb_slider et_pb_slider_fullwidth_off et_pb_slider_show_image et_pb_module et_block_module\"><div class=\"et_pb_slides\">\n<div class=\"et_pb_slide_4 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_light et_pb_text_align_left\" data-slide-id=\"divi\/slide-4\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/07\/LL-Products-EcoVadis-Score-2026.png\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/07\/LL-Products-EcoVadis-Score-2026.png 1080w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/07\/LL-Products-EcoVadis-Score-2026-980x980.png 980w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/07\/LL-Products-EcoVadis-Score-2026-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1080px, 100vw\" class=\"wp-image-22983\" title=\"LL Products EcoVadis Score 2026\" \/><\/div><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\">Ecovadis<\/h2><div class=\"et_pb_slide_content\"><p>L&amp;L Products \u6b23\u7136\u5ba3\u5e03\u5176\u6700\u65b0\u7684 EcoVadis \u53ef\u6301\u7eed\u53d1\u5c55\u8bc4\u7ea7\uff1a77\/100\u2014\u2014\u8fd9\u4f7f\u6211\u4eec\u5728\u5168\u7403\u53d7\u8bc4\u4f30\u4f01\u4e1a\u4e2d\u4f4d\u5217\u524d91\u767e\u5206\u4f4d\uff0c\u5e76\u6210\u529f\u8749\u8054\u201c\u94f6\u5956\u201d\u79f0\u53f7\u3002\u8fd9\u4e00\u6210\u5c31\u4f53\u73b0\u4e86\u6211\u4eec\u5bf9\u53ef\u6301\u7eed\u53d1\u5c55\u3001\u5408\u4e4e\u9053\u5fb7\u7684\u5546\u4e1a\u5b9e\u8df5\u3001\u5458\u5de5\u798f\u7949\u4ee5\u53ca\u8d1f\u8d23\u4efb\u91c7\u8d2d\u7684\u6301\u7eed\u627f\u8bfa\u3002<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_5 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-5\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/05\/Indian-Hills-Elementary-School-CSR.png\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/05\/Indian-Hills-Elementary-School-CSR.png 300w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2026\/05\/Indian-Hills-Elementary-School-CSR-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-22971\" title=\"Indian Hills Elementary School CSR\" \/><\/div><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\">L&L\u6559\u80b2\u57fa\u91d1\u4f1a<\/h2><div class=\"et_pb_slide_content\"><p>\u5728\u8bbf\u95ee\u7f57\u5bc6\u6b27\u793e\u533a\u5b66\u6821\u65d7\u4e0b\u7684\u5370\u5ea6\u5c71\u5c0f\u5b66\u671f\u95f4\uff0c\u6211\u4eec\u7684\u56e2\u961f\u770b\u5230\u5b66\u751f\u4eec\u6b63\u81ea\u8c6a\u5730\u4f7f\u7528L&amp;L Products\u8d44\u52a9\u7684STEM\u5de5\u5177\u8fdb\u884c\u63a2\u7d22\u3001\u642d\u5efa\u548c\u89e3\u51b3\u95ee\u9898\u2014\u2014\u8fd9\u4e00\u573a\u666f\u4f53\u73b0\u4e86\u6211\u4eec\u5bf9\u652f\u6301\u5851\u9020\u793e\u533a\u672a\u6765\u7684\u5b66\u4e60\u8005\u548c\u6559\u80b2\u5de5\u4f5c\u8005\u7684\u627f\u8bfa\u3002<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_6 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-6\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/educational-foundation.jpg\" width=\"321\" height=\"321\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/educational-foundation.jpg 321w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/educational-foundation-300x300.jpg 300w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/educational-foundation-150x150.jpg 150w\" sizes=\"(max-width: 321px) 100vw, 321px\" class=\"wp-image-1219\" \/><\/div><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\">L&L\u6559\u80b2\u57fa\u91d1\u4f1a<\/h2><div class=\"et_pb_slide_content\"><p>\u591a\u5e74\u6765\uff0cL&amp;L\u4ea7\u54c1\u57fa\u91d1\u4f1a\u4ee5\u5956\u5b66\u91d1\u548c\u52a9\u5b66\u91d1\u7684\u5f62\u5f0f\u4e3a\u6559\u80b2\u63d0\u4f9b\u4e86\u8d22\u653f\u652f\u6301\u3002L&amp;L\u4ea7\u54c1\u6559\u80b2\u57fa\u91d1\u4f1a\u4e8e1987\u5e74\u7531L&amp;L\u4ea7\u54c1\u7684\u521b\u59cb\u4ebaRobert M. Ligon\u548cW. Eugene Lane\u6210\u7acb\uff0c\u4ee5\u5e2e\u52a9L&amp;L\u5458\u5de5\u89e3\u51b3\u6210\u4eba\u6559\u80b2\u7684\u8d39\u7528\u3002L&amp;L\u4ea7\u54c1\u57fa\u91d1\u4f1a\u4e8e2018\u5e74\u7531Ligon\u5148\u751f\u548cLane\u5148\u751f\u7684\u5b50\u5973\u548c\u5b59\u5b50\u5efa\u7acb\uff0c\u4ee5\u652f\u6301\u4f4d\u4e8e\u7f8e\u56fd\u4ee5\u5916\u7684L&amp;L\u5458\u5de5\u3002<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_7 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-7\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_china.jpg\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_china.jpg 300w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_china-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-1220\" \/><\/div><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb<\/h2><div class=\"et_pb_slide_content\"><p>\u5728\u827e\u8054\uff0c\u6211\u4eec\u575a\u4fe1\u8981\u5bf9\u6211\u4eec\u7684\u793e\u533a\u4ea7\u751f\u79ef\u6781\u7684\u5f71\u54cd\u3002\u827e\u8054\u4e2d\u56fd\u6709\u5e78\u4e0e\u5f53\u5730\u4e00\u6240\u5b66\u6821\u7684\u7279\u6b8a\u5b66\u751f\u5171\u5ea6\u7f8e\u597d\u65f6\u5149\u3002\u6211\u4eec\u7684\u76ee\u6807\u5f88\u7b80\u5355\uff1a\u901a\u8fc7\u5404\u79cd\u6d3b\u52a8\u3001\u6e38\u620f\u548c\u4e00\u8d77\u4eab\u7528\u751c\u70b9\u6765\u521b\u9020\u7f8e\u597d\u56de\u5fc6\u548c\u5e86\u795d\u513f\u7ae5\u8282\u3002<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_slide_8 et_pb_slide et_pb_slide_with_image et_pb_media_alignment_center et_pb_bg_layout_dark et_pb_text_align_left\" data-slide-id=\"divi\/slide-8\"><div class=\"et_pb_container\"><div class=\"et_pb_slider_container_inner\"><div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_-_food_composting__1_.jpg\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_-_food_composting__1_.jpg 300w, https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/livingourvalues_-_food_composting__1_-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-1218\" \/><\/div><div class=\"et_pb_slide_description\"><h2 class=\"et_pb_slide_title\">\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb<\/h2><div class=\"et_pb_slide_content\"><p>\u56de\u6536\u98df\u54c1\u5bf9\u6211\u4eec\u7684\u73af\u5883\u6709\u5f88\u591a\u597d\u5904\uff0c\u4e5f\u662f\u6211\u4eec\u5458\u5de5\u7684\u65b0\u98df\u7269\u6765\u6e90\u3002\u827e\u8054\u5370\u5ea6\u4ece\u529e\u516c\u5ba4\u98df\u5802\u5f00\u59cb\u5b9e\u65bd\u98df\u7269\u5806\u80a5\u6d41\u7a0b\u3002\u5458\u5de5\u6bcf\u5929\u98df\u7528\u98df\u7269\u540e\u4f1a\u4ea7\u751f\u7ea6 100-120 \u516c\u65a4\u7684\u98df\u7269\u5783\u573e\u3002\u8fd9\u4e9b\u5783\u573e\u8fdb\u5165\u5806\u80a5\u673a\uff0c\u5f53\u5730\u56e2\u961f\u5229\u7528\u5806\u80a5\u6709\u673a\u79cd\u690d\u6c34\u679c\u548c\u852c\u83dc\u3002\u901a\u8fc7\u8fd9\u79cd\u5faa\u73af\u8fc7\u7a0b\uff0c\u5458\u5de5\u4eec\u4fbf\u53ef\u83b7\u5f97\u81ea\u5df1\u79cd\u690d\u7684\u98df\u7269\u3002<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_6 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_7 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2 class=\"h3 color-blue after-dot\">\u6211\u4eec\u7684\u5173\u952e\u4eba\u7269<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_7 et_pb_row_inner et_pb_equal_columns et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_8 et_pb_column_inner et_pb_column et_pb_column_3_8 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_number_counter_0 et_pb_number_counter et_pb_bg_layout_light et_pb_text_align_left et_pb_with_title et_pb_module et_block_module\"><div class=\"percent\"><p><span class=\"percent-value\"><\/span><span class=\"percent-sign\"><\/span><\/p><\/div><h3 class=\"title\">L&L\u6148\u5584\u57fa\u91d1\u4f1a\u6210\u7acb\uff0c \u5e2e\u52a9\u5458\u5de5\u652f\u4ed8\u6210\u4eba\u6559\u80b2\u8d39\u7528<\/h3><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_9 et_pb_column_inner et_pb_column et_pb_column_3_8 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_number_counter_1 et_pb_number_counter et_pb_bg_layout_light et_pb_text_align_left et_pb_with_title et_pb_module et_block_module\"><div class=\"percent\"><p><span class=\"percent-value\"><\/span><span class=\"percent-sign\"><\/span><\/p><\/div><h3 class=\"title\">\u5168\u7403\u96c7\u5458\u4eba\u6570<\/h3><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_8 et_pb_row_inner et_pb_equal_columns et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_10 et_pb_column_inner et_pb_column et_pb_column_3_8 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_number_counter_2 et_pb_number_counter et_pb_bg_layout_light et_pb_text_align_left et_pb_with_title et_pb_module et_block_module\"><div class=\"percent\"><p><span class=\"percent-value\"><\/span><span class=\"percent-sign\"><\/span><\/p><\/div><h3 class=\"title\">\u62e5\u6709L&L\u7f51\u70b9\u7684\u56fd\u5bb6\u6570\u91cf<\/h3><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_11 et_pb_column_inner et_pb_column et_pb_column_3_8 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_number_counter_3 et_pb_number_counter et_pb_bg_layout_light et_pb_text_align_left et_pb_with_title et_pb_module et_block_module\"><div class=\"percent\"><p><span class=\"percent-value\"><\/span><span class=\"percent-sign\"><\/span><\/p><\/div><h3 class=\"title\">\u5bb6\u65cf\u6240\u6709\u6743\u7684\u4e16\u4ee3<\/h3><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_9 et_pb_row_inner et_block_row\">\n<div class=\"et_pb_column_inner_12 et_pb_column_inner et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_dark et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u6210\u4e3a\u66f4\u5927\u7684\u4e8b\u60c5\u7684\u4e00\u90e8\u5206\u3002<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_10 et_pb_row_inner et_pb_equal_columns et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_13 et_pb_column_inner et_pb_column et_pb_column_3_8 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>\u6211\u4eec\u5728\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u65b9\u9762\u7684\u52aa\u529b--\u9488\u5bf9\u6211\u4eec\u7684\u5458\u5de5\u548c\u5546\u4e1a\u4f19\u4f34--\u6700\u7ec8\u670d\u52a1\u4e8e\u4e00\u4e2a\u603b\u4f53\u76ee\u6807\uff1a\u4f7f\u4e16\u754c\u6210\u4e3a\u4e00\u4e2a\u5bf9\u6bcf\u4e2a\u4eba\u90fd\u66f4\u7f8e\u597d\u7684\u5730\u65b9\u30022018\u5e74\uff0c\u6211\u4eec\u52a0\u5165\u4e86\u8054\u5408\u56fd\u5168\u7403\u5951\u7ea6\uff0c\u8fd9\u662f\u4e16\u754c\u4e0a\u6700\u5927\u7684\u53ef\u6301\u7eed\u53d1\u5c55\u5021\u8bae\uff0c\u6709\u8d85\u8fc71\u4e07\u5bb6\u516c\u53f8\u8d5e\u540c\u5341\u5927\u539f\u5219\u3002\u6bcf\u5e74\uff0c\u6211\u4eec\u90fd\u4f1a\u516c\u5e03\u6211\u4eec\u7684\u8fdb\u5c55\u4ea4\u6d41\uff0c\u900f\u660e\u5730\u5c55\u793a\u6211\u4eec\u6539\u8fdb\u7684\u9886\u57df\u3002<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_14 et_pb_column_inner et_pb_column et_pb_column_3_8 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_2 et_pb_image et_animated et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_support.jpg\" width=\"135\" height=\"161\" srcset=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/10\/img_we_support.jpg 135w\" sizes=\"(max-width: 135px) 100vw, 135px\" class=\"wp-image-1050\" alt=\"We support UN Global Compact\" \/><\/span><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_inner_11 et_pb_row_inner et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_15 et_pb_column_inner et_pb_column et_pb_column_3_8 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>\u4e0b\u8f09\u6211\u5011\u7684\u4f01\u696d\u793e\u6703\u8cac\u4efb\u901a\u8a0a 2023<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_16 et_pb_column_inner et_pb_column et_pb_column_3_8 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module list\" href=\"https:\/\/www.llproducts.com\/wp-content\/uploads\/2026\/04\/Corporate-Social-Responsibility-Report_2025-Final.pdf\" target=\"_blank\">\u4f01\u696d\u793e\u6703\u8cac\u4efb\u6e9d\u901a 2025<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":11761,"parent":451,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1029","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"dsm_author":{"name":"lafata","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/66f6e75e3378137d9b1a20f7ad6c54aa6acecd8466704fadf5641de9af89b844?s=96&d=mm&r=g","archive_link":"https:\/\/www.llproducts.com\/zh-cn\/news-events\/author\/lafata\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-150x150.jpg","medium":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-300x138.jpg","medium_large":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-768x353.jpg","large":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-1024x471.jpg","1536x1536":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","2048x2048":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","et-pb-post-main-image":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-1080x662.jpg","et-pb-portfolio-image":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-1080x497.jpg","et-pb-gallery-module-image-portrait":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-400x516.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","et-pb-image--responsive--desktop":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-1280x588.jpg","et-pb-image--responsive--tablet":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-980x451.jpg","et-pb-image--responsive--phone":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit-480x221.jpg","gform-image-choice-sm":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","gform-image-choice-md":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","gform-image-choice-lg":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","full":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg"},"dsm_comment_count":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb - L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/\" \/>\n<meta property=\"og:site_name\" content=\"L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T01:45:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/\",\"name\":\"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb - L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2024\\\/11\\\/ll_products_corporate_social_responsibility_csr-edit.jpg\",\"datePublished\":\"2024-10-03T15:12:44+00:00\",\"dateModified\":\"2026-07-14T01:45:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2024\\\/11\\\/ll_products_corporate_social_responsibility_csr-edit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2024\\\/11\\\/ll_products_corporate_social_responsibility_csr-edit.jpg\",\"width\":1440,\"height\":662,\"caption\":\"A woman on a bike\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/corporate-social-responsibility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u516c\u53f8\",\"item\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/company\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/#website\",\"url\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/\",\"name\":\"L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.llproducts.com\\\/zh-cn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb - L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/","og_locale":"en_US","og_type":"article","og_title":"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb","og_url":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/","og_site_name":"L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66","article_modified_time":"2026-07-14T01:45:15+00:00","og_image":[{"width":1440,"height":662,"url":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/","url":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/","name":"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb - L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66","isPartOf":{"@id":"https:\/\/www.llproducts.com\/zh-cn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/#primaryimage"},"image":{"@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/#primaryimage"},"thumbnailUrl":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","datePublished":"2024-10-03T15:12:44+00:00","dateModified":"2026-07-14T01:45:15+00:00","breadcrumb":{"@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/#primaryimage","url":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","contentUrl":"https:\/\/www.llproducts.com\/zh-cn\/wp-content\/uploads\/sites\/18\/2024\/11\/ll_products_corporate_social_responsibility_csr-edit.jpg","width":1440,"height":662,"caption":"A woman on a bike"},{"@type":"BreadcrumbList","@id":"https:\/\/www.llproducts.com\/zh-cn\/company\/corporate-social-responsibility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.llproducts.com\/zh-cn\/"},{"@type":"ListItem","position":2,"name":"\u516c\u53f8","item":"https:\/\/www.llproducts.com\/zh-cn\/company\/"},{"@type":"ListItem","position":3,"name":"\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb"}]},{"@type":"WebSite","@id":"https:\/\/www.llproducts.com\/zh-cn\/#website","url":"https:\/\/www.llproducts.com\/zh-cn\/","name":"L&amp;L\u4ea7\u54c1 - \u5e94\u7528\u5de5\u7a0b\u548c\u6750\u6599\u79d1\u5b66","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.llproducts.com\/zh-cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/pages\/1029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/comments?post=1029"}],"version-history":[{"count":1,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/pages\/1029\/revisions"}],"predecessor-version":[{"id":22985,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/pages\/1029\/revisions\/22985"}],"up":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/pages\/451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/media\/11761"}],"wp:attachment":[{"href":"https:\/\/www.llproducts.com\/zh-cn\/wp-json\/wp\/v2\/media?parent=1029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}